{"id":28,"count":4,"description":"","link":"https:\/\/prep.prezode-initiative.org\/en\/members-type\/focal-points\/","name":"Science Focal points","slug":"focal-points","taxonomy":"member-type","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Science Focal points - Prezode<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prep.prezode-initiative.org\/en\/members-type\/focal-points\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Science Focal points - Prezode\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prep.prezode-initiative.org\/en\/members-type\/focal-points\/\" \/>\n<meta property=\"og:site_name\" content=\"Prezode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/members-type\\\/focal-points\\\/\",\"url\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/members-type\\\/focal-points\\\/\",\"name\":\"Science Focal points - Prezode\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/members-type\\\/focal-points\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/members-type\\\/focal-points\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Science Focal points\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/\",\"name\":\"Prezode\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#organization\",\"name\":\"Prezode\",\"url\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.png\",\"width\":168,\"height\":118,\"caption\":\"Prezode\"},\"image\":{\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Science Focal points - Prezode","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prep.prezode-initiative.org\/en\/members-type\/focal-points\/","og_locale":"en_US","og_type":"article","og_title":"Science Focal points - Prezode","og_url":"https:\/\/prep.prezode-initiative.org\/en\/members-type\/focal-points\/","og_site_name":"Prezode","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/prep.prezode-initiative.org\/en\/members-type\/focal-points\/","url":"https:\/\/prep.prezode-initiative.org\/en\/members-type\/focal-points\/","name":"Science Focal points - Prezode","isPartOf":{"@id":"https:\/\/prep.prezode-initiative.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/prep.prezode-initiative.org\/en\/members-type\/focal-points\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/prep.prezode-initiative.org\/en\/members-type\/focal-points\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prep.prezode-initiative.org\/en\/"},{"@type":"ListItem","position":2,"name":"Science Focal points"}]},{"@type":"WebSite","@id":"https:\/\/prep.prezode-initiative.org\/en\/#website","url":"https:\/\/prep.prezode-initiative.org\/en\/","name":"Prezode","description":"","publisher":{"@id":"https:\/\/prep.prezode-initiative.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prep.prezode-initiative.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prep.prezode-initiative.org\/en\/#organization","name":"Prezode","url":"https:\/\/prep.prezode-initiative.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prep.prezode-initiative.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/prep.prezode-initiative.org\/wp-content\/uploads\/2025\/02\/logo.png","contentUrl":"https:\/\/prep.prezode-initiative.org\/wp-content\/uploads\/2025\/02\/logo.png","width":168,"height":118,"caption":"Prezode"},"image":{"@id":"https:\/\/prep.prezode-initiative.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/member-type\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/member-type"}],"about":[{"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/taxonomies\/member-type"}],"wp:post_type":[{"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/member?member-type=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}