{"id":255,"date":"2025-03-13T11:41:55","date_gmt":"2025-03-13T10:41:55","guid":{"rendered":"https:\/\/prep.prezode-initiative.org\/?page_id=255"},"modified":"2025-03-13T11:41:56","modified_gmt":"2025-03-13T10:41:56","slug":"regional-focal-points","status":"publish","type":"page","link":"https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/","title":{"rendered":"Regional focal points"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-255","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regional focal points - Prezode<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regional focal points - Prezode\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/\" \/>\n<meta property=\"og:site_name\" content=\"Prezode\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T10:41:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/regional-focal-points\\\/\",\"url\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/regional-focal-points\\\/\",\"name\":\"Regional focal points - Prezode\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#website\"},\"datePublished\":\"2025-03-13T10:41:55+00:00\",\"dateModified\":\"2025-03-13T10:41:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/regional-focal-points\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/regional-focal-points\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/regional-focal-points\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regional focal points\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/\",\"name\":\"Prezode\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#organization\",\"name\":\"Prezode\",\"url\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo.png\",\"width\":168,\"height\":118,\"caption\":\"Prezode\"},\"image\":{\"@id\":\"https:\\\/\\\/prep.prezode-initiative.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regional focal points - Prezode","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/","og_locale":"en_US","og_type":"article","og_title":"Regional focal points - Prezode","og_url":"https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/","og_site_name":"Prezode","article_modified_time":"2025-03-13T10:41:56+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/","url":"https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/","name":"Regional focal points - Prezode","isPartOf":{"@id":"https:\/\/prep.prezode-initiative.org\/en\/#website"},"datePublished":"2025-03-13T10:41:55+00:00","dateModified":"2025-03-13T10:41:56+00:00","breadcrumb":{"@id":"https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/prep.prezode-initiative.org\/en\/regional-focal-points\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prep.prezode-initiative.org\/en\/"},{"@type":"ListItem","position":2,"name":"Regional focal points"}]},{"@type":"WebSite","@id":"https:\/\/prep.prezode-initiative.org\/en\/#website","url":"https:\/\/prep.prezode-initiative.org\/en\/","name":"Prezode","description":"","publisher":{"@id":"https:\/\/prep.prezode-initiative.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prep.prezode-initiative.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prep.prezode-initiative.org\/en\/#organization","name":"Prezode","url":"https:\/\/prep.prezode-initiative.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prep.prezode-initiative.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/prep.prezode-initiative.org\/wp-content\/uploads\/2025\/02\/logo.png","contentUrl":"https:\/\/prep.prezode-initiative.org\/wp-content\/uploads\/2025\/02\/logo.png","width":168,"height":118,"caption":"Prezode"},"image":{"@id":"https:\/\/prep.prezode-initiative.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/pages\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/comments?post=255"}],"version-history":[{"count":1,"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/pages\/255\/revisions"}],"predecessor-version":[{"id":256,"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/pages\/255\/revisions\/256"}],"wp:attachment":[{"href":"https:\/\/prep.prezode-initiative.org\/en\/wp-json\/wp\/v2\/media?parent=255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}